{"id":75320,"date":"2021-10-19T15:29:24","date_gmt":"2021-10-19T20:29:24","guid":{"rendered":"https:\/\/aeronoticias.com.pe\/noticiero\/?p=75320"},"modified":"2021-10-19T19:50:59","modified_gmt":"2021-10-20T00:50:59","slug":"presidente-de-indecopi-julian-palacin-participa-en-el-encuentro-presidencial-y-sexto-gabinete-binacional-peru-bolivia","status":"publish","type":"post","link":"https:\/\/aeronoticias.com.pe\/noticiero\/nacionales\/presidente-de-indecopi-julian-palacin-participa-en-el-encuentro-presidencial-y-sexto-gabinete-binacional-peru-bolivia\/","title":{"rendered":"Presidente de Indecopi Juli\u00e1n Palacin, participa en el encuentro Presidencial y Sexto Gabinete Binacional Per\u00fa-Bolivia"},"content":{"rendered":"\n<p><strong>(Aeronoticias)<\/strong>: El Embajador Ricardo Am\u00e9rico Antonio Denegri Boza, Director General de Am\u00e9rica del Ministerio de Relaciones Exteriores del Per\u00fa, <strong><em>inform\u00f3 al Presidente Ejecutivo del Instituto Nacional de Defensa de la Competencia y de la Propiedad Intelectual (INDECOPI), su participaci\u00f3n en el encuentro Presidencial y Sexto Gabinete Binacional Per\u00fa-Bolivia que se celebrar\u00e1 en la ciudad de La Paz, Estado Plurinacional de Bolivia, el s\u00e1bado 30 de octubre pr\u00f3ximo.<\/em><\/strong><\/p>\n\n\n\n<p>El Gabinete Binacional constituye la m\u00e1xima instancia de di\u00e1logo y coordinaci\u00f3n pol\u00edtica con Bolivia y sus trabajos se estructuran en funci\u00f3n de cuatro ejes tem\u00e1ticos: <strong><em>(i) medio ambiente y recursos h\u00eddricos transfronterizos; (ii) seguridad y defensa; (iii) desarrollo econ\u00f3mico, pol\u00edticas sociales y fortalecimiento institucional; e (iv) infraestructura para la integraci\u00f3n y el desarrollo. En el manual operativo adjunto, elaborado por la canciller\u00eda boliviana.<\/em><\/strong><\/p>\n\n\n\n<p>Este encuentro binacional internacional ser\u00e1 propicio para la suscripci\u00f3n del Convenio de Cooperaci\u00f3n Interinstitucional entre INDECOPI (Per\u00fa), <em style=\"\"><b>representado por su Presidente Ejecutivo <\/b><\/em><strong><em>Juli\u00e1n Palacin Guti\u00e9rrez y SENAPI (Bolivia), que es resultado de m\u00e1s de dos a\u00f1os de negociaciones entre ambas instituciones, en el marco del compromiso 21 del Eje III del Plan de Acci\u00f3n de Ilo &#8211; Gabinete Binacional Per\u00fa-Bolivia.<\/em><\/strong><\/p>\n\n\n\n<p>El \u00a0Presidente Ejecutivo de Indecopi Juli\u00e1n Palacin \u00a0Guti\u00e9rrez\u00a0 inform\u00f3 que con la firma del convenio Indecopi-Per\u00fa con SENAPI Bolivia, se afianza la integraci\u00f3n entre ambos pa\u00edses hermanos.<\/p>\n\n\n\n<p><strong>Por: Plana Period\u00edstica<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>(Aeronoticias): El Embajador Ricardo Am\u00e9rico Antonio Denegri Boza, Director General de Am\u00e9rica del Ministerio de Relaciones Exteriores del Per\u00fa, inform\u00f3 al Presidente Ejecutivo del Instituto Nacional de Defensa de la Competencia y de la Propiedad Intelectual (INDECOPI), su participaci\u00f3n en el encuentro Presidencial y Sexto Gabinete Binacional Per\u00fa-Bolivia que se celebrar\u00e1 en la ciudad de [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":75321,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[51,38,8,30],"tags":[1367,1627],"class_list":{"0":"post-75320","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-nacional","8":"category-nacionales","9":"category-ultimas","10":"category-30","11":"tag-indecopi","12":"tag-senapi"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Presidente de Indecopi Juli\u00e1n Palacin, participa en el encuentro Presidencial y Sexto Gabinete Binacional Per\u00fa-Bolivia<\/title>\n<meta name=\"description\" content=\"Gabinete Binacional Per\u00fa-Bolivia se reunir\u00e1 en La Paz el 30 de Octubre del 2021\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/aeronoticias.com.pe\/noticiero\/nacionales\/presidente-de-indecopi-julian-palacin-participa-en-el-encuentro-presidencial-y-sexto-gabinete-binacional-peru-bolivia\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Presidente de Indecopi Juli\u00e1n Palacin, participa en el encuentro Presidencial y Sexto Gabinete Binacional Per\u00fa-Bolivia\" \/>\n<meta property=\"og:description\" content=\"Gabinete Binacional Per\u00fa-Bolivia se reunir\u00e1 en La Paz el 30 de Octubre del 2021\" \/>\n<meta property=\"og:url\" content=\"https:\/\/aeronoticias.com.pe\/noticiero\/nacionales\/presidente-de-indecopi-julian-palacin-participa-en-el-encuentro-presidencial-y-sexto-gabinete-binacional-peru-bolivia\/\" \/>\n<meta property=\"og:site_name\" content=\"Aeronoticias.com.pe\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Aeronoticias.com.pe\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-19T20:29:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-10-20T00:50:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/aeronoticias.com.pe\/noticiero\/wp-content\/uploads\/2021\/10\/Julian-INDE.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"682\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redacci\u00f3n\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@aeronoticias\" \/>\n<meta name=\"twitter:site\" content=\"@aeronoticias\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redacci\u00f3n\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/aeronoticias.com.pe\/noticiero\/nacionales\/presidente-de-indecopi-julian-palacin-participa-en-el-encuentro-presidencial-y-sexto-gabinete-binacional-peru-bolivia\/\",\"url\":\"https:\/\/aeronoticias.com.pe\/noticiero\/nacionales\/presidente-de-indecopi-julian-palacin-participa-en-el-encuentro-presidencial-y-sexto-gabinete-binacional-peru-bolivia\/\",\"name\":\"Presidente de Indecopi Juli\u00e1n Palacin, participa en el encuentro Presidencial y Sexto Gabinete Binacional Per\u00fa-Bolivia\",\"isPartOf\":{\"@id\":\"https:\/\/aeronoticias.com.pe\/noticiero\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/aeronoticias.com.pe\/noticiero\/nacionales\/presidente-de-indecopi-julian-palacin-participa-en-el-encuentro-presidencial-y-sexto-gabinete-binacional-peru-bolivia\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/aeronoticias.com.pe\/noticiero\/nacionales\/presidente-de-indecopi-julian-palacin-participa-en-el-encuentro-presidencial-y-sexto-gabinete-binacional-peru-bolivia\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/aeronoticias.com.pe\/noticiero\/wp-content\/uploads\/2021\/10\/Julian-INDE.jpeg\",\"datePublished\":\"2021-10-19T20:29:24+00:00\",\"dateModified\":\"2021-10-20T00:50:59+00:00\",\"author\":{\"@id\":\"https:\/\/aeronoticias.com.pe\/noticiero\/#\/schema\/person\/16212a617c73f78916b13194154243bd\"},\"description\":\"Gabinete Binacional Per\u00fa-Bolivia se reunir\u00e1 en La Paz el 30 de Octubre del 2021\",\"breadcrumb\":{\"@id\":\"https:\/\/aeronoticias.com.pe\/noticiero\/nacionales\/presidente-de-indecopi-julian-palacin-participa-en-el-encuentro-presidencial-y-sexto-gabinete-binacional-peru-bolivia\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/aeronoticias.com.pe\/noticiero\/nacionales\/presidente-de-indecopi-julian-palacin-participa-en-el-encuentro-presidencial-y-sexto-gabinete-binacional-peru-bolivia\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/aeronoticias.com.pe\/noticiero\/nacionales\/presidente-de-indecopi-julian-palacin-participa-en-el-encuentro-presidencial-y-sexto-gabinete-binacional-peru-bolivia\/#primaryimage\",\"url\":\"https:\/\/aeronoticias.com.pe\/noticiero\/wp-content\/uploads\/2021\/10\/Julian-INDE.jpeg\",\"contentUrl\":\"https:\/\/aeronoticias.com.pe\/noticiero\/wp-content\/uploads\/2021\/10\/Julian-INDE.jpeg\",\"width\":1024,\"height\":682},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/aeronoticias.com.pe\/noticiero\/nacionales\/presidente-de-indecopi-julian-palacin-participa-en-el-encuentro-presidencial-y-sexto-gabinete-binacional-peru-bolivia\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/aeronoticias.com.pe\/noticiero\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Presidente de Indecopi Juli\u00e1n Palacin, participa en el encuentro Presidencial y Sexto Gabinete Binacional Per\u00fa-Bolivia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/aeronoticias.com.pe\/noticiero\/#website\",\"url\":\"https:\/\/aeronoticias.com.pe\/noticiero\/\",\"name\":\"Aeronoticias.com.pe\",\"description\":\"Noticias de tranporte aereo, turismo, hoteles, gastronomia, actualidad, internacional\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/aeronoticias.com.pe\/noticiero\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/aeronoticias.com.pe\/noticiero\/#\/schema\/person\/16212a617c73f78916b13194154243bd\",\"name\":\"Redacci\u00f3n\",\"sameAs\":[\"http:\/\/Redacci\u00f3n\"],\"url\":\"https:\/\/aeronoticias.com.pe\/noticiero\/author\/celeste\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Presidente de Indecopi Juli\u00e1n Palacin, participa en el encuentro Presidencial y Sexto Gabinete Binacional Per\u00fa-Bolivia","description":"Gabinete Binacional Per\u00fa-Bolivia se reunir\u00e1 en La Paz el 30 de Octubre del 2021","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/aeronoticias.com.pe\/noticiero\/nacionales\/presidente-de-indecopi-julian-palacin-participa-en-el-encuentro-presidencial-y-sexto-gabinete-binacional-peru-bolivia\/","og_locale":"es_ES","og_type":"article","og_title":"Presidente de Indecopi Juli\u00e1n Palacin, participa en el encuentro Presidencial y Sexto Gabinete Binacional Per\u00fa-Bolivia","og_description":"Gabinete Binacional Per\u00fa-Bolivia se reunir\u00e1 en La Paz el 30 de Octubre del 2021","og_url":"https:\/\/aeronoticias.com.pe\/noticiero\/nacionales\/presidente-de-indecopi-julian-palacin-participa-en-el-encuentro-presidencial-y-sexto-gabinete-binacional-peru-bolivia\/","og_site_name":"Aeronoticias.com.pe","article_publisher":"https:\/\/www.facebook.com\/Aeronoticias.com.pe\/","article_published_time":"2021-10-19T20:29:24+00:00","article_modified_time":"2021-10-20T00:50:59+00:00","og_image":[{"width":1024,"height":682,"url":"https:\/\/aeronoticias.com.pe\/noticiero\/wp-content\/uploads\/2021\/10\/Julian-INDE.jpeg","type":"image\/jpeg"}],"author":"Redacci\u00f3n","twitter_card":"summary_large_image","twitter_creator":"@aeronoticias","twitter_site":"@aeronoticias","twitter_misc":{"Escrito por":"Redacci\u00f3n","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/aeronoticias.com.pe\/noticiero\/nacionales\/presidente-de-indecopi-julian-palacin-participa-en-el-encuentro-presidencial-y-sexto-gabinete-binacional-peru-bolivia\/","url":"https:\/\/aeronoticias.com.pe\/noticiero\/nacionales\/presidente-de-indecopi-julian-palacin-participa-en-el-encuentro-presidencial-y-sexto-gabinete-binacional-peru-bolivia\/","name":"Presidente de Indecopi Juli\u00e1n Palacin, participa en el encuentro Presidencial y Sexto Gabinete Binacional Per\u00fa-Bolivia","isPartOf":{"@id":"https:\/\/aeronoticias.com.pe\/noticiero\/#website"},"primaryImageOfPage":{"@id":"https:\/\/aeronoticias.com.pe\/noticiero\/nacionales\/presidente-de-indecopi-julian-palacin-participa-en-el-encuentro-presidencial-y-sexto-gabinete-binacional-peru-bolivia\/#primaryimage"},"image":{"@id":"https:\/\/aeronoticias.com.pe\/noticiero\/nacionales\/presidente-de-indecopi-julian-palacin-participa-en-el-encuentro-presidencial-y-sexto-gabinete-binacional-peru-bolivia\/#primaryimage"},"thumbnailUrl":"https:\/\/aeronoticias.com.pe\/noticiero\/wp-content\/uploads\/2021\/10\/Julian-INDE.jpeg","datePublished":"2021-10-19T20:29:24+00:00","dateModified":"2021-10-20T00:50:59+00:00","author":{"@id":"https:\/\/aeronoticias.com.pe\/noticiero\/#\/schema\/person\/16212a617c73f78916b13194154243bd"},"description":"Gabinete Binacional Per\u00fa-Bolivia se reunir\u00e1 en La Paz el 30 de Octubre del 2021","breadcrumb":{"@id":"https:\/\/aeronoticias.com.pe\/noticiero\/nacionales\/presidente-de-indecopi-julian-palacin-participa-en-el-encuentro-presidencial-y-sexto-gabinete-binacional-peru-bolivia\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/aeronoticias.com.pe\/noticiero\/nacionales\/presidente-de-indecopi-julian-palacin-participa-en-el-encuentro-presidencial-y-sexto-gabinete-binacional-peru-bolivia\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/aeronoticias.com.pe\/noticiero\/nacionales\/presidente-de-indecopi-julian-palacin-participa-en-el-encuentro-presidencial-y-sexto-gabinete-binacional-peru-bolivia\/#primaryimage","url":"https:\/\/aeronoticias.com.pe\/noticiero\/wp-content\/uploads\/2021\/10\/Julian-INDE.jpeg","contentUrl":"https:\/\/aeronoticias.com.pe\/noticiero\/wp-content\/uploads\/2021\/10\/Julian-INDE.jpeg","width":1024,"height":682},{"@type":"BreadcrumbList","@id":"https:\/\/aeronoticias.com.pe\/noticiero\/nacionales\/presidente-de-indecopi-julian-palacin-participa-en-el-encuentro-presidencial-y-sexto-gabinete-binacional-peru-bolivia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/aeronoticias.com.pe\/noticiero\/"},{"@type":"ListItem","position":2,"name":"Presidente de Indecopi Juli\u00e1n Palacin, participa en el encuentro Presidencial y Sexto Gabinete Binacional Per\u00fa-Bolivia"}]},{"@type":"WebSite","@id":"https:\/\/aeronoticias.com.pe\/noticiero\/#website","url":"https:\/\/aeronoticias.com.pe\/noticiero\/","name":"Aeronoticias.com.pe","description":"Noticias de tranporte aereo, turismo, hoteles, gastronomia, actualidad, internacional","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/aeronoticias.com.pe\/noticiero\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/aeronoticias.com.pe\/noticiero\/#\/schema\/person\/16212a617c73f78916b13194154243bd","name":"Redacci\u00f3n","sameAs":["http:\/\/Redacci\u00f3n"],"url":"https:\/\/aeronoticias.com.pe\/noticiero\/author\/celeste\/"}]}},"_links":{"self":[{"href":"https:\/\/aeronoticias.com.pe\/noticiero\/wp-json\/wp\/v2\/posts\/75320","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aeronoticias.com.pe\/noticiero\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aeronoticias.com.pe\/noticiero\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aeronoticias.com.pe\/noticiero\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/aeronoticias.com.pe\/noticiero\/wp-json\/wp\/v2\/comments?post=75320"}],"version-history":[{"count":0,"href":"https:\/\/aeronoticias.com.pe\/noticiero\/wp-json\/wp\/v2\/posts\/75320\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aeronoticias.com.pe\/noticiero\/wp-json\/wp\/v2\/media\/75321"}],"wp:attachment":[{"href":"https:\/\/aeronoticias.com.pe\/noticiero\/wp-json\/wp\/v2\/media?parent=75320"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aeronoticias.com.pe\/noticiero\/wp-json\/wp\/v2\/categories?post=75320"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aeronoticias.com.pe\/noticiero\/wp-json\/wp\/v2\/tags?post=75320"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}